{"id":22355,"date":"2023-09-29T10:19:25","date_gmt":"2023-09-29T02:19:25","guid":{"rendered":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg"},"modified":"2023-09-29T10:19:25","modified_gmt":"2023-09-29T02:19:25","slug":"bake-sale-bucket-cash-collection-posters-2_page-0001","status":"inherit","type":"attachment","link":"https:\/\/www.kis.edu.my\/kisnewsletter\/from-the-head-of-secondary-30-09-2023\/bake-sale-bucket-cash-collection-posters-2_page-0001\/","title":{"rendered":"Bake sale &#038; Bucket Cash Collection posters (2)_page-0001"},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-22355","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bake sale &amp; Bucket Cash Collection posters (2)_page-0001 - KIS Newsletter<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bake sale &amp; Bucket Cash Collection posters (2)_page-0001 - KIS Newsletter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg\" \/>\n<meta property=\"og:site_name\" content=\"KIS Newsletter\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/fb.com\/kinabaluinternationalschool\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg\",\"url\":\"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg\",\"name\":\"Bake sale & Bucket Cash Collection posters (2)_page-0001 - KIS Newsletter\",\"isPartOf\":{\"@id\":\"https:\/\/www.kis.edu.my\/kisnewsletter\/#website\"},\"datePublished\":\"2023-09-29T02:19:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.kis.edu.my\/kisnewsletter\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"From the Head of Secondary 30.09.2023\",\"item\":\"https:\/\/www.kis.edu.my\/kisnewsletter\/from-the-head-of-secondary-30-09-2023\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bake sale &#038; Bucket Cash Collection posters (2)_page-0001\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kis.edu.my\/kisnewsletter\/#website\",\"url\":\"https:\/\/www.kis.edu.my\/kisnewsletter\/\",\"name\":\"Kinabalu International School\",\"description\":\"KIS Newsletter\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kis.edu.my\/kisnewsletter\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bake sale & Bucket Cash Collection posters (2)_page-0001 - KIS Newsletter","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg","og_locale":"en_US","og_type":"article","og_title":"Bake sale & Bucket Cash Collection posters (2)_page-0001 - KIS Newsletter","og_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg","og_site_name":"KIS Newsletter","article_publisher":"http:\/\/fb.com\/kinabaluinternationalschool","og_image":[{"width":1920,"height":2560,"url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg","url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg","name":"Bake sale & Bucket Cash Collection posters (2)_page-0001 - KIS Newsletter","isPartOf":{"@id":"https:\/\/www.kis.edu.my\/kisnewsletter\/#website"},"datePublished":"2023-09-29T02:19:25+00:00","breadcrumb":{"@id":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kis.edu.my\/kisnewsletter\/"},{"@type":"ListItem","position":2,"name":"From the Head of Secondary 30.09.2023","item":"https:\/\/www.kis.edu.my\/kisnewsletter\/from-the-head-of-secondary-30-09-2023\/"},{"@type":"ListItem","position":3,"name":"Bake sale &#038; Bucket Cash Collection posters (2)_page-0001"}]},{"@type":"WebSite","@id":"https:\/\/www.kis.edu.my\/kisnewsletter\/#website","url":"https:\/\/www.kis.edu.my\/kisnewsletter\/","name":"Kinabalu International School","description":"KIS Newsletter","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kis.edu.my\/kisnewsletter\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-scaled.jpg'><img decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-225x300.jpg 225w, https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-768x1024.jpg 768w, https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-1152x1536.jpg 1152w, https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-1536x2048.jpg 1536w, https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-255x340.jpg 255w, https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-scaled.jpg 1920w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"1920","height":"2560","file":"2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-scaled.jpg","sizes":{"medium":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-225x300.jpg","width":"225","height":"300","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-225x300.jpg"},"large":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-768x1024.jpg","width":"768","height":"1024","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-768x1024.jpg"},"thumbnail":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-150x150.jpg","width":"150","height":"150","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-150x150.jpg"},"medium_large":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-768x1024.jpg","width":"768","height":"1024","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-768x1024.jpg"},"1536x1536":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-1152x1536.jpg","width":"1152","height":"1536","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-1152x1536.jpg"},"2048x2048":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-1536x2048.jpg","width":"1536","height":"2048","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-1536x2048.jpg"},"thumb_139x89":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-139x89.jpg","width":"139","height":"89","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-139x89.jpg"},"thumb_277x337":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-277x337.jpg","width":"277","height":"337","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-277x337.jpg"},"thumb_50x50":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-50x50.jpg","width":"50","height":"50","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-50x50.jpg"},"thumb_80x80":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-80x80.jpg","width":"80","height":"80","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-80x80.jpg"},"thumb_263x263":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-263x263.jpg","width":"263","height":"263","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-263x263.jpg"},"thumb_409x258":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-409x258.jpg","width":"409","height":"258","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-409x258.jpg"},"thumb_278x178":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-278x178.jpg","width":"278","height":"178","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-278x178.jpg"},"thumb_554x674":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-554x674.jpg","width":"554","height":"674","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-554x674.jpg"},"thumb_100x100":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-100x100.jpg","width":"100","height":"100","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-100x100.jpg"},"thumb_526x526":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-526x526.jpg","width":"526","height":"526","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-526x526.jpg"},"thumb_818x516":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-818x516.jpg","width":"818","height":"516","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-818x516.jpg"},"post-thumbnail":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-255x340.jpg","width":"255","height":"340","mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-255x340.jpg"},"full":{"file":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-scaled.jpg","width":1920,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0"},"original_image":"Bake-sale-Bucket-Cash-Collection-posters-2_page-0001.jpg"},"post":22343,"source_url":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-content\/uploads\/2023\/09\/Bake-sale-Bucket-Cash-Collection-posters-2_page-0001-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-json\/wp\/v2\/media\/22355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kis.edu.my\/kisnewsletter\/wp-json\/wp\/v2\/comments?post=22355"}]}}